{"id":231,"date":"2023-03-20T10:13:26","date_gmt":"2023-03-20T09:13:26","guid":{"rendered":"https:\/\/mi-piace.nl\/beta\/home\/"},"modified":"2025-04-19T08:58:19","modified_gmt":"2025-04-19T06:58:19","slug":"lookbook","status":"publish","type":"page","link":"https:\/\/mi-piace.nl\/beta\/en\/lookbook\/","title":{"rendered":"lookbook"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/home.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-231","page","type-page","status-publish","hentry","image-hover-transition-effect"],"acf":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/mi-piace.nl\/beta\/en\/wp-json\/wp\/v2\/pages\/231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mi-piace.nl\/beta\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mi-piace.nl\/beta\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mi-piace.nl\/beta\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mi-piace.nl\/beta\/en\/wp-json\/wp\/v2\/comments?post=231"}],"version-history":[{"count":6,"href":"https:\/\/mi-piace.nl\/beta\/en\/wp-json\/wp\/v2\/pages\/231\/revisions"}],"predecessor-version":[{"id":16700,"href":"https:\/\/mi-piace.nl\/beta\/en\/wp-json\/wp\/v2\/pages\/231\/revisions\/16700"}],"wp:attachment":[{"href":"https:\/\/mi-piace.nl\/beta\/en\/wp-json\/wp\/v2\/media?parent=231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}